{"id":1558,"date":"2021-05-11T06:43:03","date_gmt":"2021-05-11T06:43:03","guid":{"rendered":"https:\/\/heshimardc.net\/v1\/?p=1558"},"modified":"2021-05-11T06:43:05","modified_gmt":"2021-05-11T06:43:05","slug":"que-reste-t-il-de-la-gratuite-de-lenseignement","status":"publish","type":"post","link":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/","title":{"rendered":"Que reste-t-il de la gratuit\u00e9 de l&rsquo;enseignement ?"},"content":{"rendered":"\n<p class=\"has-drop-cap\">Comme promis lors de son investiture le 24 janvier 2019, <a href=\"https:\/\/heshimardc.net\/v1\/2020\/10\/22\/ted-beleshayi-la-gratuite-de-lenseignement-de-base-est-la-meilleure-decision-de-ces-vingt-dernieres-annees\/\" target=\"_blank\" rel=\"noreferrer noopener\">le pr\u00e9sident F\u00e9lix-Antoine Tshisekedi a d\u00e9cr\u00e9t\u00e9 la gratuit\u00e9 de l&rsquo;enseignement de base \u00e0 partir de l&rsquo;ann\u00e9e scolaire 2019- 2020.<\/a> Une d\u00e9cision courageuse inscrite dans la Constitution, mais jamais concr\u00e9tis\u00e9e par son pr\u00e9d\u00e9cesseur, Joseph Kabila, faute de moyens.&nbsp;<\/p>\n\n\n\n<p>&nbsp;Effectivement, selon les projections des acteurs du secteur r\u00e9unis dans une Table ronde fin ao\u00fbt 2019, quelques jours avant la rentr\u00e9e scolaire, il faut un budget annuel autour de 2 milliards de dollars&nbsp;pour r\u00e9ussir la r\u00e9forme de la gratuit\u00e9 de l&rsquo;enseignement de base qui implique plusieurs facteurs induits. Parmi lesquels, le paiement de salaires des enseignants N.U (nouvelles unit\u00e9s) et N.P (non-pay\u00e9s), des frais de fonctionnement des \u00e9coles ou encore la construction de nouvelles infrastructures scolaires pour contenir un flux suppl\u00e9mentaire de plus de 2 millions d&rsquo;\u00e9l\u00e8ves chaque ann\u00e9e.<\/p>\n\n\n\n<p><a href=\"https:\/\/heshimardc.net\/v1\/2020\/10\/22\/une-rentree-scolaire-sur-fond-dinterrogations\/\" target=\"_blank\" rel=\"noreferrer noopener\">Sauf que, entre-temps, le budget national qui devait soutenir cette charge ne s&rsquo;est pas am\u00e9lior\u00e9. Alors que le gouvernement projetait 11 milliards de dollars en 2020, le pays n&rsquo;a m\u00eame pas \u00e9t\u00e9 en mesure de mobiliser, la&nbsp;moiti\u00e9 de ce montant. <\/a>Le Tr\u00e9sor public n&rsquo;a r\u00e9ussi \u00e0 mobiliser en ressources propres qu&rsquo;entre 3 et 4 milliards de dollars, tous engloutis ou presque dans les d\u00e9penses courantes (salaires et fonctionnement des institutions).<\/p>\n\n\n\n<p class=\"has-text-color has-medium-font-size\" style=\"color:#a32365\"><strong>La justice a frapp\u00e9<\/strong><\/p>\n\n\n\n<p>La crise \u00e9conomique cons\u00e9cutive \u00e0 la Covid-19 n&rsquo;a pas non plus arrang\u00e9 les choses. Les soutiens internationaux \u00e0 la gratuit\u00e9 tardent \u00e0 se concr\u00e9tiser. La Banque mondiale qui a promis jusqu&rsquo;\u00e0 1 milliard de dollars, a suspendu, d\u00e9but 2021, le processus suite aux enqu\u00eates ouvertes sur les \u00e9coles fictives et d\u00e9tournements syst\u00e9matiques des fonds.<\/p>\n\n\n\n<p>Le 25 mars 2021, le directeur du service de paie des enseignants (SECOPE) et l&rsquo;inspecteur g\u00e9n\u00e9ral du minist\u00e8re ont \u00e9t\u00e9 condamn\u00e9s \u00e0 20 ans de prison pour d\u00e9tournement de fonds de la gratuit\u00e9.<\/p>\n\n\n\n<p>Le ministre d&rsquo;\u00c9tat charg\u00e9 de l&rsquo;EPST, Willy Bakonga, serait aussi sur le coup des poursuites, d\u00e8s la sortie du nouveau gouvernement. Le 21 avril, alors qu&rsquo;il voulait prendre un avion pour Paris \u00e0 partir de Brazzaville, il sera appr\u00e9hend\u00e9 par les services migratoires avec une importante somme d&rsquo;argent, selon l&rsquo;Association congolaise d&rsquo;acc\u00e8s \u00e0 la justice (ACAJ). Son proc\u00e8s devrait aussi s&rsquo;ouvrir incessamment et servir de p\u00e9dagogie, question aussi de convaincre la Banque mondiale de renouer avec le financement de la gratuit\u00e9. D\u00e9j\u00e0, des milliers d&rsquo;\u00e9coles fictives et celles fonctionnant sur base de faux arr\u00eat\u00e9s ont \u00e9t\u00e9 d\u00e9sactiv\u00e9es du syst\u00e8me, avant que le secr\u00e9tariat g\u00e9n\u00e9ral \u00e0 l\u2019EPST parle d\u2019un traitement des dossiers de ces&nbsp;&nbsp;\u00e9coles \u00ab au cas par cas \u00bb.<\/p>\n\n\n\n<p class=\"has-text-color has-medium-font-size\" style=\"color:#b1204b\"><strong>Infrastructures jamais construites<\/strong><\/p>\n\n\n\n<p>Face \u00e0 tous ces probl\u00e8mes, la mise en \u0153uvre de la gratuit\u00e9 bat de l&rsquo;aile au pays. Des infrastructures suppl\u00e9mentaires n&rsquo;ont jamais \u00e9t\u00e9 construites malgr\u00e9 le nombre croissant d&rsquo;\u00e9l\u00e8ves chaque ann\u00e9e. Aussi, les enseignants N.U et N.P attendent d\u00e9sesp\u00e9r\u00e9ment d&rsquo;entrer sur le listing de paie, les frais scolaires de parents qui le permettaient de toucher des primes n&rsquo;existant plus.<\/p>\n\n\n\n<p>&nbsp;En plus, les frais de fonctionnement des \u00e9coles arrivent \u00e0 compte-gouttes. Le 12 avril, c&rsquo;est in extremis que la d\u00e9l\u00e9gation syndicale a suspendu la gr\u00e8ve dans les \u00e9coles primaires&nbsp;qui r\u00e9clamaient deux mois des frais de fonctionnement impay\u00e9s suite \u00e0 un d\u00e9but d&rsquo;apurement par le gouvernement.<\/p>\n\n\n\n<p>Des enseignants d\u00e9motiv\u00e9s, c&rsquo;est les enfants qui en p\u00e2tissent. Certaines \u00e9coles ont fini par trouver des arrangements avec les parents en payant officieusement une partie des frais. A ce rythme, cette r\u00e9forme pourtant salutaire n&rsquo;a plus un avenir certain.<\/p>\n\n\n\n<p>Socrate NSIMBA&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Bien qu\u2019inscrite dans la Constitution, la gratuit\u00e9 de l\u2019enseignement n\u2019a jamais connu son effectivit\u00e9 jusqu\u2019\u00e0 l\u2019arriv\u00e9e du pr\u00e9sident Tshisekedi qui a mis un point d\u2019honneur \u00e0 sa mat\u00e9rialisation en d\u00e9pit des difficult\u00e9s rencontr\u00e9es. Qu\u2019en est-il aujourd\u2019hui de son \u00e9volution ?<\/p>\n","protected":false},"author":2,"featured_media":1559,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[175],"tags":[182],"class_list":["post-1558","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-societe","tag-rdc"],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v23.3 - https:\/\/yoast.com\/wordpress\/plugins\/seo\/ -->\n<title>Que reste-t-il de la gratuit\u00e9 de l&#039;enseignement ? - HESHIMA MAGAZINE<\/title>\n<meta name=\"description\" content=\"Comme promis lors de son investiture le 24 janvier 2019, le pr\u00e9sident F\u00e9lix-Antoine Tshisekedi a d\u00e9cr\u00e9t\u00e9 la gratuit\u00e9 de l&#039;enseignement de base \u00e0 partir de l&#039;ann\u00e9e scolaire 2019- 2020. Une d\u00e9cision courageuse inscrite dans la Constitution, mais jamais concr\u00e9tis\u00e9e par son pr\u00e9d\u00e9cesseur, Joseph Kabila, faute de moyens.\" \/>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Que reste-t-il de la gratuit\u00e9 de l&#039;enseignement ? - HESHIMA MAGAZINE\" \/>\n<meta property=\"og:description\" content=\"Comme promis lors de son investiture le 24 janvier 2019, le pr\u00e9sident F\u00e9lix-Antoine Tshisekedi a d\u00e9cr\u00e9t\u00e9 la gratuit\u00e9 de l&#039;enseignement de base \u00e0 partir de l&#039;ann\u00e9e scolaire 2019- 2020. Une d\u00e9cision courageuse inscrite dans la Constitution, mais jamais concr\u00e9tis\u00e9e par son pr\u00e9d\u00e9cesseur, Joseph Kabila, faute de moyens.\" \/>\n<meta property=\"og:url\" content=\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/\" \/>\n<meta property=\"og:site_name\" content=\"HESHIMA MAGAZINE\" \/>\n<meta property=\"article:publisher\" content=\"https:\/\/www.facebook.com\/heshimamagazine\" \/>\n<meta property=\"article:published_time\" content=\"2021-05-11T06:43:03+00:00\" \/>\n<meta property=\"article:modified_time\" content=\"2021-05-11T06:43:05+00:00\" \/>\n<meta property=\"og:image\" content=\"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-14.07.54.jpeg\" \/>\n\t<meta property=\"og:image:width\" content=\"515\" \/>\n\t<meta property=\"og:image:height\" content=\"393\" \/>\n\t<meta property=\"og:image:type\" content=\"image\/jpeg\" \/>\n<meta name=\"author\" content=\"RedactionH\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<meta name=\"twitter:creator\" content=\"@HeshimaMag\" \/>\n<meta name=\"twitter:site\" content=\"@HeshimaMag\" \/>\n<meta name=\"twitter:label1\" content=\"\u00c9crit par\" \/>\n\t<meta name=\"twitter:data1\" content=\"RedactionH\" \/>\n\t<meta name=\"twitter:label2\" content=\"Dur\u00e9e de lecture estim\u00e9e\" \/>\n\t<meta name=\"twitter:data2\" content=\"3 minutes\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\/\/schema.org\",\"@graph\":[{\"@type\":\"Article\",\"@id\":\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#article\",\"isPartOf\":{\"@id\":\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/\"},\"author\":{\"name\":\"RedactionH\",\"@id\":\"https:\/\/heshimardc.net\/v1\/#\/schema\/person\/c74a2d47650131f158dc4a027547a532\"},\"headline\":\"Que reste-t-il de la gratuit\u00e9 de l&rsquo;enseignement ?\",\"datePublished\":\"2021-05-11T06:43:03+00:00\",\"dateModified\":\"2021-05-11T06:43:05+00:00\",\"mainEntityOfPage\":{\"@id\":\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/\"},\"wordCount\":630,\"publisher\":{\"@id\":\"https:\/\/heshimardc.net\/v1\/#organization\"},\"image\":{\"@id\":\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-14.07.54.jpeg\",\"keywords\":[\"RDC\"],\"articleSection\":[\"Soci\u00e9t\u00e9\"],\"inLanguage\":\"fr-FR\"},{\"@type\":\"WebPage\",\"@id\":\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/\",\"url\":\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/\",\"name\":\"Que reste-t-il de la gratuit\u00e9 de l'enseignement ? - HESHIMA MAGAZINE\",\"isPartOf\":{\"@id\":\"https:\/\/heshimardc.net\/v1\/#website\"},\"primaryImageOfPage\":{\"@id\":\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#primaryimage\"},\"image\":{\"@id\":\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#primaryimage\"},\"thumbnailUrl\":\"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-14.07.54.jpeg\",\"datePublished\":\"2021-05-11T06:43:03+00:00\",\"dateModified\":\"2021-05-11T06:43:05+00:00\",\"description\":\"Comme promis lors de son investiture le 24 janvier 2019, le pr\u00e9sident F\u00e9lix-Antoine Tshisekedi a d\u00e9cr\u00e9t\u00e9 la gratuit\u00e9 de l'enseignement de base \u00e0 partir de l'ann\u00e9e scolaire 2019- 2020. Une d\u00e9cision courageuse inscrite dans la Constitution, mais jamais concr\u00e9tis\u00e9e par son pr\u00e9d\u00e9cesseur, Joseph Kabila, faute de moyens.\",\"breadcrumb\":{\"@id\":\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/\"]}]},{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#primaryimage\",\"url\":\"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-14.07.54.jpeg\",\"contentUrl\":\"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-14.07.54.jpeg\",\"width\":515,\"height\":393},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Accueil\",\"item\":\"https:\/\/heshimardc.net\/v1\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Que reste-t-il de la gratuit\u00e9 de l&rsquo;enseignement ?\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\/\/heshimardc.net\/v1\/#website\",\"url\":\"https:\/\/heshimardc.net\/v1\/\",\"name\":\"HESHIMA MAGAZINE\",\"description\":\"Le magazine Congolais qui bat au rythme de l&#039;actualit\u00e9\",\"publisher\":{\"@id\":\"https:\/\/heshimardc.net\/v1\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\/\/heshimardc.net\/v1\/?s={search_term_string}\"},\"query-input\":\"required name=search_term_string\"}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\/\/heshimardc.net\/v1\/#organization\",\"name\":\"HESHIMA MAGAZINE\",\"url\":\"https:\/\/heshimardc.net\/v1\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/heshimardc.net\/v1\/#\/schema\/logo\/image\/\",\"url\":\"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2020\/09\/logo.png\",\"contentUrl\":\"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2020\/09\/logo.png\",\"width\":99,\"height\":130,\"caption\":\"HESHIMA MAGAZINE\"},\"image\":{\"@id\":\"https:\/\/heshimardc.net\/v1\/#\/schema\/logo\/image\/\"},\"sameAs\":[\"https:\/\/www.facebook.com\/heshimamagazine\",\"https:\/\/x.com\/HeshimaMag\"]},{\"@type\":\"Person\",\"@id\":\"https:\/\/heshimardc.net\/v1\/#\/schema\/person\/c74a2d47650131f158dc4a027547a532\",\"name\":\"RedactionH\",\"image\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\/\/heshimardc.net\/v1\/#\/schema\/person\/image\/\",\"url\":\"https:\/\/secure.gravatar.com\/avatar\/a52112f8496f362a38bf46c70ca9e956?s=96&d=mm&r=g\",\"contentUrl\":\"https:\/\/secure.gravatar.com\/avatar\/a52112f8496f362a38bf46c70ca9e956?s=96&d=mm&r=g\",\"caption\":\"RedactionH\"},\"sameAs\":[\"http:\/\/www.heshimardc.net\"],\"url\":\"https:\/\/heshimardc.net\/v1\/author\/redactionh\/\"}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Que reste-t-il de la gratuit\u00e9 de l'enseignement ? - HESHIMA MAGAZINE","description":"Comme promis lors de son investiture le 24 janvier 2019, le pr\u00e9sident F\u00e9lix-Antoine Tshisekedi a d\u00e9cr\u00e9t\u00e9 la gratuit\u00e9 de l'enseignement de base \u00e0 partir de l'ann\u00e9e scolaire 2019- 2020. Une d\u00e9cision courageuse inscrite dans la Constitution, mais jamais concr\u00e9tis\u00e9e par son pr\u00e9d\u00e9cesseur, Joseph Kabila, faute de moyens.","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/","og_locale":"fr_FR","og_type":"article","og_title":"Que reste-t-il de la gratuit\u00e9 de l'enseignement ? - HESHIMA MAGAZINE","og_description":"Comme promis lors de son investiture le 24 janvier 2019, le pr\u00e9sident F\u00e9lix-Antoine Tshisekedi a d\u00e9cr\u00e9t\u00e9 la gratuit\u00e9 de l'enseignement de base \u00e0 partir de l'ann\u00e9e scolaire 2019- 2020. Une d\u00e9cision courageuse inscrite dans la Constitution, mais jamais concr\u00e9tis\u00e9e par son pr\u00e9d\u00e9cesseur, Joseph Kabila, faute de moyens.","og_url":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/","og_site_name":"HESHIMA MAGAZINE","article_publisher":"https:\/\/www.facebook.com\/heshimamagazine","article_published_time":"2021-05-11T06:43:03+00:00","article_modified_time":"2021-05-11T06:43:05+00:00","og_image":[{"width":515,"height":393,"url":"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-14.07.54.jpeg","type":"image\/jpeg"}],"author":"RedactionH","twitter_card":"summary_large_image","twitter_creator":"@HeshimaMag","twitter_site":"@HeshimaMag","twitter_misc":{"\u00c9crit par":"RedactionH","Dur\u00e9e de lecture estim\u00e9e":"3 minutes"},"schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"Article","@id":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#article","isPartOf":{"@id":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/"},"author":{"name":"RedactionH","@id":"https:\/\/heshimardc.net\/v1\/#\/schema\/person\/c74a2d47650131f158dc4a027547a532"},"headline":"Que reste-t-il de la gratuit\u00e9 de l&rsquo;enseignement ?","datePublished":"2021-05-11T06:43:03+00:00","dateModified":"2021-05-11T06:43:05+00:00","mainEntityOfPage":{"@id":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/"},"wordCount":630,"publisher":{"@id":"https:\/\/heshimardc.net\/v1\/#organization"},"image":{"@id":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#primaryimage"},"thumbnailUrl":"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-14.07.54.jpeg","keywords":["RDC"],"articleSection":["Soci\u00e9t\u00e9"],"inLanguage":"fr-FR"},{"@type":"WebPage","@id":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/","url":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/","name":"Que reste-t-il de la gratuit\u00e9 de l'enseignement ? - HESHIMA MAGAZINE","isPartOf":{"@id":"https:\/\/heshimardc.net\/v1\/#website"},"primaryImageOfPage":{"@id":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#primaryimage"},"image":{"@id":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#primaryimage"},"thumbnailUrl":"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-14.07.54.jpeg","datePublished":"2021-05-11T06:43:03+00:00","dateModified":"2021-05-11T06:43:05+00:00","description":"Comme promis lors de son investiture le 24 janvier 2019, le pr\u00e9sident F\u00e9lix-Antoine Tshisekedi a d\u00e9cr\u00e9t\u00e9 la gratuit\u00e9 de l'enseignement de base \u00e0 partir de l'ann\u00e9e scolaire 2019- 2020. Une d\u00e9cision courageuse inscrite dans la Constitution, mais jamais concr\u00e9tis\u00e9e par son pr\u00e9d\u00e9cesseur, Joseph Kabila, faute de moyens.","breadcrumb":{"@id":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/"]}]},{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#primaryimage","url":"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-14.07.54.jpeg","contentUrl":"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2021\/05\/WhatsApp-Image-2021-05-03-at-14.07.54.jpeg","width":515,"height":393},{"@type":"BreadcrumbList","@id":"https:\/\/heshimardc.net\/v1\/2021\/05\/11\/que-reste-t-il-de-la-gratuite-de-lenseignement\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Accueil","item":"https:\/\/heshimardc.net\/v1\/"},{"@type":"ListItem","position":2,"name":"Que reste-t-il de la gratuit\u00e9 de l&rsquo;enseignement ?"}]},{"@type":"WebSite","@id":"https:\/\/heshimardc.net\/v1\/#website","url":"https:\/\/heshimardc.net\/v1\/","name":"HESHIMA MAGAZINE","description":"Le magazine Congolais qui bat au rythme de l&#039;actualit\u00e9","publisher":{"@id":"https:\/\/heshimardc.net\/v1\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/heshimardc.net\/v1\/?s={search_term_string}"},"query-input":"required name=search_term_string"}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/heshimardc.net\/v1\/#organization","name":"HESHIMA MAGAZINE","url":"https:\/\/heshimardc.net\/v1\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/heshimardc.net\/v1\/#\/schema\/logo\/image\/","url":"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2020\/09\/logo.png","contentUrl":"https:\/\/heshimardc.net\/v1\/wp-content\/uploads\/2020\/09\/logo.png","width":99,"height":130,"caption":"HESHIMA MAGAZINE"},"image":{"@id":"https:\/\/heshimardc.net\/v1\/#\/schema\/logo\/image\/"},"sameAs":["https:\/\/www.facebook.com\/heshimamagazine","https:\/\/x.com\/HeshimaMag"]},{"@type":"Person","@id":"https:\/\/heshimardc.net\/v1\/#\/schema\/person\/c74a2d47650131f158dc4a027547a532","name":"RedactionH","image":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/heshimardc.net\/v1\/#\/schema\/person\/image\/","url":"https:\/\/secure.gravatar.com\/avatar\/a52112f8496f362a38bf46c70ca9e956?s=96&d=mm&r=g","contentUrl":"https:\/\/secure.gravatar.com\/avatar\/a52112f8496f362a38bf46c70ca9e956?s=96&d=mm&r=g","caption":"RedactionH"},"sameAs":["http:\/\/www.heshimardc.net"],"url":"https:\/\/heshimardc.net\/v1\/author\/redactionh\/"}]}},"amp_enabled":true,"_links":{"self":[{"href":"https:\/\/heshimardc.net\/v1\/wp-json\/wp\/v2\/posts\/1558"}],"collection":[{"href":"https:\/\/heshimardc.net\/v1\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/heshimardc.net\/v1\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/heshimardc.net\/v1\/wp-json\/wp\/v2\/users\/2"}],"replies":[{"embeddable":true,"href":"https:\/\/heshimardc.net\/v1\/wp-json\/wp\/v2\/comments?post=1558"}],"version-history":[{"count":2,"href":"https:\/\/heshimardc.net\/v1\/wp-json\/wp\/v2\/posts\/1558\/revisions"}],"predecessor-version":[{"id":1574,"href":"https:\/\/heshimardc.net\/v1\/wp-json\/wp\/v2\/posts\/1558\/revisions\/1574"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/heshimardc.net\/v1\/wp-json\/wp\/v2\/media\/1559"}],"wp:attachment":[{"href":"https:\/\/heshimardc.net\/v1\/wp-json\/wp\/v2\/media?parent=1558"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/heshimardc.net\/v1\/wp-json\/wp\/v2\/categories?post=1558"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/heshimardc.net\/v1\/wp-json\/wp\/v2\/tags?post=1558"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}